{"id":266,"count":1,"description":"","link":"https:\/\/vejerproperties.com\/es\/estado\/reservado\/","name":"Reservado","slug":"reservado","taxonomy":"property_status","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reservado Archives - De la Luz Properties<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vejerproperties.com\/es\/estado\/reservado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reservado Archives - De la Luz Properties\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vejerproperties.com\/es\/estado\/reservado\/\" \/>\n<meta property=\"og:site_name\" content=\"De la Luz Properties\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/vejerproperties.com\\\/es\\\/estado\\\/reservado\\\/\",\"url\":\"https:\\\/\\\/vejerproperties.com\\\/es\\\/estado\\\/reservado\\\/\",\"name\":\"Reservado Archives - De la Luz Properties\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vejerproperties.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vejerproperties.com\\\/es\\\/estado\\\/reservado\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vejerproperties.com\\\/es\\\/estado\\\/reservado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vejerproperties.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reservado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vejerproperties.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vejerproperties.com\\\/es\\\/\",\"name\":\"De la Luz Properties\",\"description\":\"Spanish Estate Agent\",\"publisher\":{\"@id\":\"https:\\\/\\\/vejerproperties.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vejerproperties.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vejerproperties.com\\\/es\\\/#organization\",\"name\":\"De la Luz Properties\",\"url\":\"https:\\\/\\\/vejerproperties.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vejerproperties.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vejerproperties.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/de-la-luz-logo.png\",\"contentUrl\":\"https:\\\/\\\/vejerproperties.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/de-la-luz-logo.png\",\"width\":181,\"height\":71,\"caption\":\"De la Luz Properties\"},\"image\":{\"@id\":\"https:\\\/\\\/vejerproperties.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reservado Archives - De la Luz Properties","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vejerproperties.com\/es\/estado\/reservado\/","og_locale":"es_ES","og_type":"article","og_title":"Reservado Archives - De la Luz Properties","og_url":"https:\/\/vejerproperties.com\/es\/estado\/reservado\/","og_site_name":"De la Luz Properties","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/vejerproperties.com\/es\/estado\/reservado\/","url":"https:\/\/vejerproperties.com\/es\/estado\/reservado\/","name":"Reservado Archives - De la Luz Properties","isPartOf":{"@id":"https:\/\/vejerproperties.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/vejerproperties.com\/es\/estado\/reservado\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/vejerproperties.com\/es\/estado\/reservado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vejerproperties.com\/es\/"},{"@type":"ListItem","position":2,"name":"Reservado"}]},{"@type":"WebSite","@id":"https:\/\/vejerproperties.com\/es\/#website","url":"https:\/\/vejerproperties.com\/es\/","name":"De la Luz Properties","description":"Spanish Estate Agent","publisher":{"@id":"https:\/\/vejerproperties.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vejerproperties.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vejerproperties.com\/es\/#organization","name":"De la Luz Properties","url":"https:\/\/vejerproperties.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vejerproperties.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/vejerproperties.com\/wp-content\/uploads\/2018\/02\/de-la-luz-logo.png","contentUrl":"https:\/\/vejerproperties.com\/wp-content\/uploads\/2018\/02\/de-la-luz-logo.png","width":181,"height":71,"caption":"De la Luz Properties"},"image":{"@id":"https:\/\/vejerproperties.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vejerproperties.com\/es\/wp-json\/wp\/v2\/property_status\/266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vejerproperties.com\/es\/wp-json\/wp\/v2\/property_status"}],"about":[{"href":"https:\/\/vejerproperties.com\/es\/wp-json\/wp\/v2\/taxonomies\/property_status"}],"wp:post_type":[{"href":"https:\/\/vejerproperties.com\/es\/wp-json\/wp\/v2\/properties?property_status=266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}